{"id":143582,"date":"2025-02-20T07:00:40","date_gmt":"2025-02-20T06:00:40","guid":{"rendered":"https:\/\/www.seopress.org\/fr\/?p=143582"},"modified":"2025-10-09T11:51:28","modified_gmt":"2025-10-09T09:51:28","slug":"nouveaux-modeles-dia-ameliorations-pour-le-bloc-table-des-matieres-seopress-8-6","status":"publish","type":"post","link":"https:\/\/www.seopress.org\/fr\/newsroom\/nouveautes-produit\/seopress-8-6\/","title":{"rendered":"Nouveaux mod\u00e8les d&rsquo;IA, am\u00e9liorations pour le bloc Table des Mati\u00e8res &#8211; SEOPress 8.6"},"content":{"rendered":"<p><strong>SEOPress 8.6 est d\u00e9sormais disponible.<\/strong> Nous vous encourageons \u00e0 mettre \u00e0 jour votre site d\u00e8s que possible pour profiter des derni\u00e8res fonctionnalit\u00e9s, am\u00e9liorations et correctifs.<\/p>\n<h2>\ud83c\udf89 Nouveaux mod\u00e8les d&rsquo;IA disponibles<\/h2>\n<p>Nous avons ajout\u00e9 les derniers mod\u00e8les d&rsquo;IA d&rsquo;<a href=\"https:\/\/www.seopress.org\/fr\/fonctionnalites\/openai\/\">OpenAI<\/a> pour <a href=\"https:\/\/www.seopress.org\/fr\/support\/guides\/generez-vos-metadonnees-seo-avec-openai\/\">g\u00e9n\u00e9rer automatiquement des m\u00e9tadonn\u00e9es SEO<\/a> en fonction du contenu et de la langue de votre publication, ainsi que des textes alternatifs automatiques pour vos m\u00e9dias.<\/p>\n<p>La liste des mod\u00e8les d&rsquo;IA disponibles dans <a href=\"https:\/\/www.seopress.org\/fr\/extensions-seo-wordpress\/seopress-pro\/\">SEOPress PRO<\/a> est d\u00e9sormais la suivante:<\/p>\n<ul>\n<li>GPT-4o Mini<\/li>\n<li>GPT-4o<\/li>\n<li>GPT-4<\/li>\n<li>GPT-3.5-Turbo<\/li>\n<\/ul>\n<p>Nous avons \u00e9galement optimis\u00e9 les prompts envoy\u00e9es \u00e0 OpenAI pour mieux prendre en charge la grammaire et la typographie en fonction de la langue de votre publication. Cela devrait \u00e9viter d&rsquo;avoir des majuscules par exemple lorsque ce n&rsquo;est pas n\u00e9cessaire.<\/p>\n<h2 id=\"%f0%9f%8e%89-other-news\">\ud83c\udf89 Bloc Table des Mati\u00e8res am\u00e9lior\u00e9<\/h2>\n<p>Suite \u00e0 plusieurs retours d&rsquo;utilisateurs, notre bloc \u00ab\u00a0table des mati\u00e8res\u00a0\u00bb est encore plus pratique \u00e0 utiliser. La section en cours est d\u00e9sormais marqu\u00e9e comme active visuellement dans le bloc (comme sur Wikip\u00e9dia).<\/p>\n<p>Et vous pouvez enfin appliquer une position \u00e9pingl\u00e9 et\/ou un bloc de d\u00e9tails pour l&rsquo;afficher\/le masquer.<\/p>\n<p>Notre d\u00e9mo vid\u00e9o pour mieux comprendre les possibilit\u00e9s offertes :<\/p>\n<p><iframe loading=\"lazy\" title=\"How to Use SEOPress Table of Contents Block (TOC) - Full Guide &amp; Demo\" width=\"856\" height=\"482\" src=\"https:\/\/www.youtube.com\/embed\/4I3PIQsyIHI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<h2 id=\"%f0%9f%8e%89-other-news\">\ud83c\udf89 Autres nouveaut\u00e9s<\/h2>\n<p>Cette nouvelle version de SEOPress apporte \u00e9galement son lot d&rsquo;am\u00e9liorations et de correctifs, notamment\u00a0:<\/p>\n<ul>\n<li>le d\u00e9lai d&rsquo;expiration de Page Speed \u200b\u200bInsights est pass\u00e9 de 30 \u00e0 120 s ;<\/li>\n<li>la gestion des erreurs pour le widget GA4 permet de comprendre rapidement tout probl\u00e8me ;<\/li>\n<li>une meilleure compatibilit\u00e9 avec WPML et son module compl\u00e9mentaire WooCommerce ;<\/li>\n<li>un crash avec la fonctionnalit\u00e9 de lien interne de la m\u00e9tabox SEO universelle dans un cas sp\u00e9cifique ;<\/li>\n<li>certaines variables dynamiques pour les pages d&rsquo;auteur affichaient des donn\u00e9es incorrectes dans certains cas ;<\/li>\n<li>et bien plus encore !<\/li>\n<\/ul>\n<p>Pour les d\u00e9veloppeurs, nous avons ajout\u00e9 un hook suppl\u00e9mentaire\u00a0:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.seopress.org\/fr\/support\/filtrer-le-lien-prev-next-dans-le-head-des-archives-paginees\/\">seopress_titles_paged_rel<\/a> pour filtrer les liens rel du code source<\/li>\n<\/ul>\n<p>N&rsquo;oubliez pas de vous abonner \u00e0 notre newsletter pour suivre nos derni\u00e8res mises \u00e0 jour de produits et recevoir les derni\u00e8res\u00a0actualit\u00e9s Google\u00a0:<\/p>\n<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_1' ><form method='post' enctype='multipart\/form-data'  id='gform_1'  action='\/fr\/wp-json\/wp\/v2\/posts\/143582' data-formid='1' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_1' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_1_6\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_6'>Instagram<\/label><div class='ginput_container'><input name='input_6' id='input_1_6' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_1_6'>Ce champ n\u2019est utilis\u00e9 qu\u2019\u00e0 des fins de validation et devrait rester inchang\u00e9.<\/div><\/div><div id=\"field_1_1\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-two-thirds gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_1_1'>E-mail<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(N\u00e9cessaire)<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_1' id='input_1_1' type='email' value='' class='form-control large'   placeholder='Saisissez votre adresse email' aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_1_2\" class=\"gfield gfield--type-html gfield--input-type-html gfield--width-third gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><button class=\"btn btn-primary\" onclick=\"document.getElementById('gform_submit_button_1').click();\">\nS'abonner\n<\/button><\/div><div id=\"field_1_4\" class=\"gfield gfield--type-html gfield--input-type-html gfield--width-half gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  >J'accepte que SEOPress stocke et utilise mon adresse e-mail afin de m'envoyer une newsletter. <a href=\"https:\/\/www.seopress.org\/fr\/politique-confidentialite\/\">En savoir plus sur notre politique de confidentialit\u00e9<\/a><\/div><div id=\"field_1_5\" class=\"gfield gfield--type-turnstile gfield--input-type-turnstile gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_turnstile'><div class=\"cf-turnstile\" id=\"cf-turnstile_1\" data-js-turnstile data-response-field-name=\"cf-turnstile-response_1\" data-theme=\"auto\" data-size=\"\" data-sitekey=\"0x4AAAAAAABgaVshlWxe3qWW\"><\/div><\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <button type=\"submit\" id=\"gform_submit_button_1\" class=\"gform_button button btn btn-primary\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"submit\">S'abonner<\/button> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_1' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_1' id='gform_theme_1' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_1' id='gform_style_settings_1' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_1' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='1' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='beYqb\/IRwhO1WTuCPRn32Fkmy4EtPbYtspuraitogJY7kw04JXzvpzCt+h9mOsW0xXBtKXwnhSfvys05lQvBnHl1FPEmBVD7LGQSERcHRP6QQrs=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_1' value='WyJbXSIsIjkwN2ViYjJmZmNiNDgyYTg0MWIyNGVjMjkwODNmMWQwIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_1' id='gform_target_page_number_1' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_1' id='gform_source_page_number_1' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"218\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 1, 'https:\/\/www.seopress.org\/fr\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_1').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_1');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_1').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_1').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_1').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_1').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_1').val();gformInitSpinner( 1, 'https:\/\/www.seopress.org\/fr\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [1, current_page]);window['gf_submitting_1'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_1').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [1]);window['gf_submitting_1'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_1').text());}else{jQuery('#gform_1').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"1\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_1\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_1\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_1\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 1, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n\n<p><span class=\"p-3 bg-light rounded fw-bold d-inline-block w-100\">Vous aimez SEOPress ? S&rsquo;il vous pla\u00eet, rendez-nous service : laissez un avis 5 \u00e9toiles sur le r\u00e9pertoire officiel des extensions WordPress pour nous aider. Presque 1 100 avis ! Merci \u00e0 tous !<br \/>\n<a href=\"https:\/\/wordpress.org\/support\/plugin\/wp-seopress\/reviews\/#new-post\" target=\"_blank\" rel=\"nofollow noopener\">Laisser un avis 5 \u00e9toiles<\/a><\/span><\/p>\n<h2>Journal des modifications<\/h2>\n<p>Cette mise \u00e0 jour contient les modifications suivantes (<a href=\"https:\/\/www.seopress.org\/fr\/support\/journal-modifications\/seopress-free-pro\/\">journal des modifications complet ici<\/a>)\u00a0:<\/p>\n<pre>* NEW Update AI models (now available: GPT-4o Mini, GPT-4o, GPT-4, GPT-3.5-Turbo)\r\n* NEW Enhancements for Table of Contents block\r\n* NEW Wizard enhancements for a better user experience\r\n* NEW \"seopress_titles_paged_rel\" hook to filter the paged rel links in the head section (https:\/\/www.seopress.org\/support\/hooks\/filter-rel-nextprev-link-in-head-of-paginated-archive-pages\/)\r\n* INFO Remove noarchive meta robots tag as it's not longer supported by Google\r\n* INFO Ask AI to respect the grammar and typing of the language\r\n* INFO Add error handling for Google Analytics stats in dashboard widget (SEO, Analytics, Google Analytics tab, Stats in dashboard section)\r\n* INFO Increase timeout for Page Speed Insights API (from 30 to 120 seconds)\r\n* FIX i18n POT file\r\n* FIX Default OG:IMAGE for Shop page\r\n* FIX Default settings for term taxonomies meta title \/ description\r\n* FIX No \/product-category\/ in URL when using WooCommerce and WPML Multilingual CMS + WooCommerce Multilingual &amp; Multicurrency\r\n* FIX User meta tags for author\r\n* FIX AI: Alt text for images uploaded from Gravity Forms\r\n* FIX undefined $language with AI in specific cases\r\n* FIX JS error attachment when using AI\r\n* FIX Incorrect meta title\/desc counters between classic SEO metabox and Universal one\r\n* FIX Bricks builder compatibility issue with SEOPress PRO\r\n* FIX PHP Warning: Attempt to read property \"display_name\" Author on null in Breadcrumbs\r\n* FIX Internal linking suggestions JS error\r\n* FIX Google Analytics \/ Matomo widgets if no data\r\n* FIX Fatal error on plugin deactivation<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>SEOPress 8.6 est d\u00e9sormais disponible. Nous vous encourageons \u00e0 mettre \u00e0 jour votre site&#8230;<\/p>\n","protected":false},"author":1,"featured_media":143613,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2025\/02\/seopress-8-6-social-fr@2x-scaled.jpg","_seopress_social_fb_img_attachment_id":143614,"_seopress_social_fb_img_width":2560,"_seopress_social_fb_img_height":1280,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2025\/02\/seopress-8-6-social-fr@2x-scaled.jpg","_seopress_social_twitter_img_attachment_id":143614,"_seopress_social_twitter_img_width":2560,"_seopress_social_twitter_img_height":1280,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","editor_notices":[],"footnotes":""},"categories":[98],"tags":[135,134],"class_list":["post-143582","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nouveautes-produit","tag-editeur-de-blocs","tag-ia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/posts\/143582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/comments?post=143582"}],"version-history":[{"count":0,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/posts\/143582\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/media\/143613"}],"wp:attachment":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/media?parent=143582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/categories?post=143582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/tags?post=143582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}