{"id":56295,"date":"2022-09-15T07:00:54","date_gmt":"2022-09-15T05:00:54","guid":{"rendered":"https:\/\/www.seopress.org\/fr\/?p=56295"},"modified":"2025-10-09T17:25:56","modified_gmt":"2025-10-09T15:25:56","slug":"introduction-a-google-analytics-pour-wordpress","status":"publish","type":"post","link":"https:\/\/www.seopress.org\/fr\/newsroom\/reportage\/introduction-google-analytics-wordpress\/","title":{"rendered":"Introduction \u00e0 Google Analytics pour WordPress"},"content":{"rendered":"<p>Google Analytics est offert en tant que service gratuit par Google depuis 2005 et c\u2019est actuellement, et de loin, l\u2019outil d\u2019analyse Web le plus populaire au monde. Vous pouvez utiliser Google Analytics sur un site WordPress pour obtenir des informations d\u00e9taill\u00e9es sur les visiteurs de votre site et mesurer vos progr\u00e8s dans l\u2019augmentation du trafic et la g\u00e9n\u00e9ration de revenus.<\/p>\n<p>Une fois le code Google Analytics install\u00e9 sur une page Web, il peut enregistrer et envoyer des informations au serveur Google Analytics. Vous donnant ainsi une vue sur\u00a0les actions du visiteur sur cette page ainsi que des informations sur sa position g\u00e9ographique et son appareil. Gr\u00e2ce aux cookies, Google peut suivre les visiteurs d\u2019une page \u00e0 une autre et reconna\u00eetre des utilisateurs quand ils reviennent sur un site. Les propri\u00e9taires de sites peuvent ensuite acc\u00e9der \u00e0 ces donn\u00e9es via le service en ligne<a href=\"https:\/\/analytics.google.com\/\" target=\"_blank\" rel=\"noopener\"> https:\/\/analytics.google.com<\/a>.<\/p>\n<figure id=\"attachment_56334\" aria-labelledby=\"figcaption_attachment_56334\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/1-how-google-analytics-works.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56334\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/1-how-google-analytics-works.png\" alt=\"Illustration du fonctionnement de Google Analytics\" width=\"1206\" height=\"404\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/1-how-google-analytics-works.png 1206w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/1-how-google-analytics-works-768x257.png 768w\" sizes=\"auto, (max-width: 1206px) 100vw, 1206px\" \/><\/a><figcaption id=\"figcaption_attachment_56334\" class=\"wp-caption-text mt-3 mb-5 fst-italic\">Illustration du <a href=\"https:\/\/support.google.com\/analytics\/answer\/12159447\" target=\"_blank\" rel=\"noopener\">fonctionnement de Google Analytics<\/a><\/figcaption><\/figure>\n<p>Les rapports de Google Analytics fournissent des informations telles que le nombre de visites par jour, l\u2019emplacement g\u00e9ographique des utilisateurs, l\u2019origine de leur trafic (recherche organique, recherche payante, r\u00e9seaux sociaux, etc.), la technologie qu\u2019ils ont utilis\u00e9e lors de leur visite sur le site et les pages les plus populaires. Les KPI (indicateurs cl\u00e9s de performances) fournis par Google permettent \u00e9galement aux propri\u00e9taires de sites d\u2019\u00e9valuer la qualit\u00e9 de leur trafic sur la base d\u2019engagement et de conversions (par exemple les achats en ligne et les revenus des sites e-commerce).<\/p>\n<figure id=\"attachment_56335\" aria-labelledby=\"figcaption_attachment_56335\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/2-example-google-analytics-report.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56335\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/2-example-google-analytics-report.png\" alt=\"Exemple de rapport Google Analytics\" width=\"3800\" height=\"2160\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/2-example-google-analytics-report.png 3800w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/2-example-google-analytics-report-768x437.png 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/2-example-google-analytics-report-1536x873.png 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/2-example-google-analytics-report-2048x1164.png 2048w\" sizes=\"auto, (max-width: 3800px) 100vw, 3800px\" \/><\/a><figcaption id=\"figcaption_attachment_56335\" class=\"wp-caption-text mt-3 mb-5 fst-italic\">Exemple de rapport Google Analytics<\/figcaption><\/figure>\n<p>Si vous voulez s\u00e9rieusement augmenter le trafic de votre site WordPress, vous devriez installer Google Analytics ou un service \u00e9quivalent pour analyser le trafic et les conversions au fil du temps. Plus vos analyses Web sont pr\u00e9cises, plus vous serez en mesure de comprendre votre audience, d\u2019am\u00e9liorer votre contenu et r\u00e9f\u00e9rencer vos pages dans les moteurs de recherche comme Google.<\/p>\n<figure id=\"attachment_85680\" aria-labelledby=\"figcaption_attachment_85680\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/support\/ebooks\/analysez-votre-audience-avec-google-analytics\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-85680 size-full\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/15_analytics-fr@2x-scaled.jpg\" alt=\"&lt;a href=&quot;https:\/\/www.seopress.org\/fr\/support\/ebooks\/analysez-votre-audience-avec-google-analytics\/&quot;&gt;D\u00e9couvrez les secrets des strat\u00e9gies de r\u00e9f\u00e9rencement efficaces - Procurez-vous notre ebook d\u00e8s aujourd'hui !&lt;\/a&gt;\" width=\"2560\" height=\"1280\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/15_analytics-fr@2x-scaled.jpg 2560w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/15_analytics-fr@2x-768x384.jpg 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/15_analytics-fr@2x-1536x768.jpg 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/15_analytics-fr@2x-2048x1024.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><figcaption id=\"figcaption_attachment_85680\" class=\"wp-caption-text mt-3 mb-5 fst-italic\"><a href=\"https:\/\/www.seopress.org\/fr\/support\/ebooks\/analysez-votre-audience-avec-google-analytics\/\">D\u00e9couvrez les secrets des strat\u00e9gies de r\u00e9f\u00e9rencement efficaces &#8211; Procurez-vous notre ebook d\u00e8s aujourd&rsquo;hui !<\/a><\/figcaption><\/figure>\n<h2>Google Analytics 4 ou Universal Analytics ?<\/h2>\n<p>Si vous commencez \u00e0 utiliser Google Analytics maintenant, vous utiliserez par d\u00e9faut Google Analytics 4 (ou GA4). Il s\u2019agit de la quatri\u00e8me version de Google Analytics et d\u2019un service enti\u00e8rement nouveau.<\/p>\n<p>Les sites utilisant la version pr\u00e9c\u00e9dente, Universal Analytics ou GA3, ne pourront pas migrer les donn\u00e9es vers Google Analytics 4 et le service cessera de fonctionner fin juin 2023. Il est donc recommand\u00e9 aux utilisateurs d\u2019Universal Analytics de passer \u00e0 GA4 d\u00e8s que possible. Vous pouvez installer les deux versions de Google Analytics sur WordPress en utilisant SEOPress. Voir notre guide <a href=\"https:\/\/www.seopress.org\/fr\/support\/guides\/debutez-avec-google-analytics\/\">ici<\/a>.<\/p>\n<p>Google fournit un <a href=\"https:\/\/support.google.com\/analytics\/?hl=fr#topic=10737980\" target=\"_blank\" rel=\"noopener\">guide<\/a> si vous avez besoin d\u2019aide pour passer d\u2019Universal Analytics vers GA4, mais il ne propose pas la migration de vos donn\u00e9es.<\/p>\n<figure id=\"attachment_56336\" aria-labelledby=\"figcaption_attachment_56336\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56336\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics.png\" alt=\"4 traffic acquisition report in google analytics\" width=\"3800\" height=\"2160\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics.png 3800w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics-768x437.png 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics-1536x873.png 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics-2048x1164.png 2048w\" sizes=\"auto, (max-width: 3800px) 100vw, 3800px\" \/><\/a><figcaption id=\"figcaption_attachment_56336\" class=\"wp-caption-text mt-3 mb-5 fst-italic\">4 traffic acquisition report in google analytics<\/figcaption><\/figure>\n<figure id=\"attachment_56342\" aria-labelledby=\"figcaption_attachment_56342\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/3-google-analytics-migration-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56342\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/3-google-analytics-migration-scaled.jpg\" alt=\"Illustration de la migration GA4 depuis Google\" width=\"2560\" height=\"815\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/3-google-analytics-migration-scaled.jpg 2560w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/3-google-analytics-migration-768x244.jpg 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/3-google-analytics-migration-1536x489.jpg 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/3-google-analytics-migration-2048x652.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><figcaption id=\"figcaption_attachment_56342\" class=\"wp-caption-text mt-3 mb-5 fst-italic\">Illustration de la migration GA4 depuis Google<\/figcaption><\/figure>\n<h2>Comment Google Analytics contribue-t-il \u00e0 am\u00e9liorer le r\u00e9f\u00e9rencement ?<\/h2>\n<p>Il y a de nombreuses ann\u00e9es, les donn\u00e9es de Google Analytics incluaient le d\u00e9tail des requ\u00eates de recherche \u00e0 l\u2019origine du trafic depuis le moteur de recherche Google. Pour cette raison c\u2019\u00e9tait un outil de r\u00e9f\u00e9rencement essentiel. Ces donn\u00e9es ne sont plus disponibles dans Google Analytics (mais dans Google Search Console), mais Google Analytics reste n\u00e9anmoins utile pour analyser votre r\u00e9f\u00e9rencement.<\/p>\n<p>Les rapports d\u2019acquisition dans Google Analytics indiquent le nombre de visites par jour sur le site et incluent une ventilation par source de trafic. La vue par d\u00e9faut affiche le trafic par regroupement de canaux. Les principaux canaux sont :<\/p>\n<ul>\n<li>Organic Search &#8211; Recherche organique<\/li>\n<li>Paid Search &#8211; Recherche payante<\/li>\n<li>Display \u2013 Publicit\u00e9 Display<\/li>\n<li>Paid Social \u2013 Publicit\u00e9 sur les r\u00e9seaux sociaux<\/li>\n<li>Organic Social \u2013 R\u00e9seaux sociaux<\/li>\n<li>Email \u2013 Emailing<\/li>\n<li>Referral \u2013 Liens d\u2019autres sites<\/li>\n<li>Direct \u2013 Acc\u00e8s directs au site<\/li>\n<\/ul>\n<p>La recherche organique est le trafic que vous obtenez des moteurs de recherche, \u00e0 l\u2019exclusion de toute publicit\u00e9 payante telle que Google Ads. Suivre les donn\u00e9es sur votre trafic de moteurs de recherche au fil du temps peut \u00eatre un bon indicateur de vos progr\u00e8s (ou de vos probl\u00e8mes) en r\u00e9f\u00e9rencement. Dans la capture d\u2019\u00e9cran ci-dessous, nous voyons les donn\u00e9es du <a href=\"https:\/\/www.googlemerchandisestore.com\/\" target=\"_blank\" rel=\"noopener\">Merchandise Store de Google<\/a> pour ao\u00fbt 2022.<\/p>\n<figure id=\"attachment_56336\" aria-labelledby=\"figcaption_attachment_56336\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56336\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics.png\" alt=\"Rapport d\u2019acquisition de trafic dans Google Analytics\" width=\"3800\" height=\"2160\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics.png 3800w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics-768x437.png 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics-1536x873.png 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/4-traffic-acquisition-report-in-google-analytics-2048x1164.png 2048w\" sizes=\"auto, (max-width: 3800px) 100vw, 3800px\" \/><\/a><figcaption id=\"figcaption_attachment_56336\" class=\"wp-caption-text mt-3 mb-5 fst-italic\">Rapport d\u2019acquisition de trafic dans Google Analytics<\/figcaption><\/figure>\n<p>Notez que ce rapport affiche un tableau de donn\u00e9es par canal. Nous pouvons voir que la recherche organique a g\u00e9n\u00e9r\u00e9 45 422 Sessions (c\u2019est-\u00e0-dire des visites sur le site) et 33 168 Sessions avec engagement. Les Sessions avec engagement sont des visites qui ne sont pas simplement arriv\u00e9es sur une page et qui sont ensuite parties. Un visiteur engag\u00e9 a fait soit d\u00e9filer la page, cliqu\u00e9 sur un \u00e9l\u00e9ment de la page, visionn\u00e9 une vid\u00e9o sur la page ou encore cliqu\u00e9 sur un lien pour visiter une autre page.<\/p>\n<p>En faisant d\u00e9filer vers la droite (voir l\u2019image ci-dessous), nous pouvons voir que Organic Search a fourni 648 achats en ligne, g\u00e9n\u00e9rant un revenu de 92.586,01 $.<\/p>\n<figure id=\"attachment_56337\" aria-labelledby=\"figcaption_attachment_56337\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/5-traffic-acquisition-report-in-google-analytics-scroll-right.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56337\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/5-traffic-acquisition-report-in-google-analytics-scroll-right.png\" alt=\"Le m\u00eame rapport d\u2019acquisition de trafic avec conversions\" width=\"3800\" height=\"2160\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/5-traffic-acquisition-report-in-google-analytics-scroll-right.png 3800w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/5-traffic-acquisition-report-in-google-analytics-scroll-right-768x437.png 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/5-traffic-acquisition-report-in-google-analytics-scroll-right-1536x873.png 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/5-traffic-acquisition-report-in-google-analytics-scroll-right-2048x1164.png 2048w\" sizes=\"auto, (max-width: 3800px) 100vw, 3800px\" \/><\/a><figcaption id=\"figcaption_attachment_56337\" class=\"wp-caption-text mt-3 mb-5 fst-italic\">Le m\u00eame rapport d\u2019acquisition de trafic avec conversions<\/figcaption><\/figure>\n<p>Ces rapports vous donnent un aper\u00e7u r\u00e9el des sources de trafic qui g\u00e9n\u00e8rent de \u00ab\u00a0bonnes\u00a0\u00bb visites sur votre site Web et peuvent vous donner une id\u00e9e r\u00e9elle de la valeur g\u00e9n\u00e9r\u00e9e par le r\u00e9f\u00e9rencement.<\/p>\n<h2>Le rapport Pages et \u00e9crans dans Google Analytics 4<\/h2>\n<p>Un autre rapport que vous pouvez trouver utile pour le r\u00e9f\u00e9rencement est le rapport Pages et \u00e9crans. Ce rapport affiche le nombre de pages vues pour chaque page visit\u00e9e sur votre site au cours de la p\u00e9riode s\u00e9lectionn\u00e9e.<\/p>\n<figure id=\"attachment_56338\" aria-labelledby=\"figcaption_attachment_56338\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/6-pages-and-screens-report.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56338\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/6-pages-and-screens-report.png\" alt=\"Rapport de pages et d\u2019\u00e9crans dans Google Analytics\" width=\"3800\" height=\"2160\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/6-pages-and-screens-report.png 3800w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/6-pages-and-screens-report-768x437.png 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/6-pages-and-screens-report-1536x873.png 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/6-pages-and-screens-report-2048x1164.png 2048w\" sizes=\"auto, (max-width: 3800px) 100vw, 3800px\" \/><\/a><figcaption id=\"figcaption_attachment_56338\" class=\"wp-caption-text mt-3 mb-5 fst-italic\">Rapport de pages et d\u2019\u00e9crans dans Google Analytics<\/figcaption><\/figure>\n<p>Class\u00e9 par pages vues, ce rapport affiche d\u2019abord les pages les plus populaires. Si vous avez un blog avec de nombreuses pages, vous trouverez int\u00e9ressant de voir quels articles sont les plus lus. Vous pouvez \u00e9galement voir combien de temps les utilisateurs passent sur chaque page. Vous devez \u00e9galement \u00eatre attentif aux publications qui re\u00e7oivent tr\u00e8s peu de pages vues des moteurs de recherche ou avec des visites tr\u00e8s courtes.<\/p>\n<p>Pour tout rapport dans Google Analytics, vous pouvez modifier l\u2019audience analys\u00e9e de \u00ab\u00a0Tous les utilisateurs\u00a0\u00bb \u00e0 celle que vous d\u00e9finissez. Dans la capture d\u2019\u00e9cran ci-dessous, nous avons cr\u00e9\u00e9 une audience qui ne contient que des sessions provenant de Organic Search uniquement pour mieux analyser notre trafic des moteurs de recherche.<\/p>\n<figure id=\"attachment_56339\" aria-labelledby=\"figcaption_attachment_56339\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/7-pages-and-screens-report-filtered.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56339\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/7-pages-and-screens-report-filtered.png\" alt=\"Rapport Pages et \u00e9crans filtr\u00e9s pour les utilisateurs de la recherche organique\" width=\"3800\" height=\"2160\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/7-pages-and-screens-report-filtered.png 3800w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/7-pages-and-screens-report-filtered-768x437.png 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/7-pages-and-screens-report-filtered-1536x873.png 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/7-pages-and-screens-report-filtered-2048x1164.png 2048w\" sizes=\"auto, (max-width: 3800px) 100vw, 3800px\" \/><\/a><figcaption id=\"figcaption_attachment_56339\" class=\"wp-caption-text mt-3 mb-5 fst-italic\">Rapport Pages et \u00e9crans filtr\u00e9s pour les utilisateurs de la recherche organique<\/figcaption><\/figure>\n<p>Le rapport Pages et \u00e9crans avec le filtre appliqu\u00e9 n\u2019affiche d\u00e9sormais que des pages vues et les sessions provenant des moteurs de recherche. Les pages avec le plus de pages vues par les moteurs de recherche peuvent \u00eatre consid\u00e9r\u00e9es comme celles avec le meilleur r\u00e9f\u00e9rencement. Inversement, les pages qui re\u00e7oivent tr\u00e8s peu de trafic ou pas de trafic du tout peuvent n\u00e9cessiter une attention. Dans certains cas, il peut \u00eatre int\u00e9ressant d\u2019envisager la suppression de pages qui ne re\u00e7oivent aucun trafic des moteurs de recherche.<\/p>\n<h2>Rapports d\u00e9mographiques<\/h2>\n<p>Si vous ne ciblez qu\u2019une zone g\u00e9ographique sp\u00e9cifique (un pays, une r\u00e9gion ou une ville), vous trouverez tr\u00e8s utile de voir l\u2019emplacement g\u00e9ographique de vos visiteurs. Vous pouvez \u00e9galement filtrer votre rapport pour ne voir appara\u00eetre que le trafic de cette zone.<\/p>\n<figure id=\"attachment_56340\" aria-labelledby=\"figcaption_attachment_56340\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/8-demographic-overview.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-56340 size-full\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/8-demographic-overview.png\" alt=\"Vue d\u00e9mographique g\u00e9n\u00e9rale\" width=\"3800\" height=\"2160\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/8-demographic-overview.png 3800w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/8-demographic-overview-768x437.png 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/8-demographic-overview-1536x873.png 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/8-demographic-overview-2048x1164.png 2048w\" sizes=\"auto, (max-width: 3800px) 100vw, 3800px\" \/><\/a><figcaption id=\"figcaption_attachment_56340\" class=\"wp-caption-text mt-3 mb-5 fst-italic\">Vue d\u00e9mographique g\u00e9n\u00e9rale<\/figcaption><\/figure>\n<h2>Prochaines \u00e9tapes<\/h2>\n<p>Dans cet article, nous vous avons montr\u00e9 quelques exemples d\u2019utilisation de Google Analytics 4. Nous explorerons les donn\u00e9es et les rapports fournis par Google Analytics plus en d\u00e9tail dans l\u2019article \u00ab\u00a0<a href=\"https:\/\/www.seopress.org\/fr\/newsroom\/reportage\/introduction-google-analytics-wordpress\/\">Prise en main de Google Analytics 4<\/a> \u00bb. Si vous n\u2019avez pas encore Google Analytics ou si vous ne l\u2019avez pas install\u00e9 sur votre site WordPress, consultez l\u2019article \u00ab <a href=\"https:\/\/www.seopress.org\/fr\/newsroom\/reportage\/configurer-installer-google-analytics-4-wordpress\/\">Comment configurer et installer Google Analytics 4 sur WordPress<\/a>\u00a0\u00bb.<\/p>\n<p>D\u00e9couvrez notre s\u00e9rie d&rsquo;articles passionnants qui explorent diff\u00e9rentes facettes d&rsquo;une th\u00e9matique commune, vous offrant ainsi une vision compl\u00e8te : <strong>Analysez votre audience avec Google Analytics<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.seopress.org\/fr\/newsroom\/reportage\/configurer-installer-google-analytics-4-wordpress\/\">Comment configurer et installer Google Analytics 4 sur WordPress<\/a><\/li>\n<li><a href=\"https:\/\/www.seopress.org\/fr\/newsroom\/etude-de-cas\/commencer-google-analytics-4\/\">Premiers pas avec Google Analytics 4<\/a><\/li>\n<li><a href=\"https:\/\/www.seopress.org\/fr\/newsroom\/reportage\/alternatives-google-analytics-wordpress\/\">Alternatives a\u0300 Google Analytics pour les sites WordPress<\/a><\/li>\n<li><a href=\"https:\/\/www.seopress.org\/fr\/newsroom\/reportage\/20-conseils-bien-utiliser-google-analytics-4-wordpress\/\">20 conseils pour bien utiliser Google Analytics 4 et WordPress<\/a><\/li>\n<\/ul>\n<figure id=\"attachment_85680\" aria-labelledby=\"figcaption_attachment_85680\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/support\/ebooks\/analysez-votre-audience-avec-google-analytics\/\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-85680 size-full\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/15_analytics-fr@2x-scaled.jpg\" alt=\"&lt;a href=&quot;https:\/\/www.seopress.org\/fr\/support\/ebooks\/analysez-votre-audience-avec-google-analytics\/&quot;&gt;D\u00e9couvrez les secrets des strat\u00e9gies de r\u00e9f\u00e9rencement efficaces - Procurez-vous notre ebook d\u00e8s aujourd'hui !&lt;\/a&gt;\" width=\"2560\" height=\"1280\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/15_analytics-fr@2x-scaled.jpg 2560w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/15_analytics-fr@2x-768x384.jpg 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/15_analytics-fr@2x-1536x768.jpg 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/11\/15_analytics-fr@2x-2048x1024.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><figcaption id=\"figcaption_attachment_85680\" class=\"wp-caption-text mt-3 mb-5 fst-italic\"><a href=\"https:\/\/www.seopress.org\/fr\/support\/ebooks\/analysez-votre-audience-avec-google-analytics\/\">D\u00e9couvrez les secrets des strat\u00e9gies de r\u00e9f\u00e9rencement efficaces &#8211; Procurez-vous notre ebook d\u00e8s aujourd&rsquo;hui !<\/a><\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Google Analytics est offert en tant que service gratuit par Google depuis 2005 et&#8230;<\/p>\n","protected":false},"author":1,"featured_media":56323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"Vous pouvez utiliser Google Analytics sur un site WordPress pour obtenir des informations d\u00e9taill\u00e9es sur les visiteurs de votre site et mesurer vos progr\u00e8s dans l'augmentation du trafic et la g\u00e9n\u00e9ration de revenus.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"Vous pouvez utiliser Google Analytics sur un site WordPress pour obtenir des informations d\u00e9taill\u00e9es sur les visiteurs de votre site et mesurer vos progr\u00e8s dans l'augmentation du trafic et la g\u00e9n\u00e9ration de revenus.","_seopress_social_fb_img":"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/analytics-seo-intro-fr@2x-scaled.jpg","_seopress_social_fb_img_attachment_id":56322,"_seopress_social_fb_img_width":2560,"_seopress_social_fb_img_height":1280,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"Vous pouvez utiliser Google Analytics sur un site WordPress pour obtenir des informations d\u00e9taill\u00e9es sur les visiteurs de votre site et mesurer vos progr\u00e8s dans l'augmentation du trafic et la g\u00e9n\u00e9ration de revenus.","_seopress_social_twitter_img":"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2022\/09\/analytics-seo-intro-fr@2x-scaled.jpg","_seopress_social_twitter_img_attachment_id":56322,"_seopress_social_twitter_img_width":2560,"_seopress_social_twitter_img_height":1280,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[{"_seopress_pro_rich_snippets_type":"none"}],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","editor_notices":[],"footnotes":""},"categories":[97],"tags":[128],"class_list":["post-56295","post","type-post","status-publish","format-standard","has-post-thumbnail","category-reportage","tag-analytics"],"acf":[],"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/posts\/56295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/comments?post=56295"}],"version-history":[{"count":0,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/posts\/56295\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/media\/56323"}],"wp:attachment":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/media?parent=56295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/categories?post=56295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/tags?post=56295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}