{"id":72546,"date":"2023-03-02T08:00:31","date_gmt":"2023-03-02T07:00:31","guid":{"rendered":"https:\/\/www.seopress.org\/fr\/?p=72546"},"modified":"2025-10-09T15:33:11","modified_gmt":"2025-10-09T13:33:11","slug":"lactualite-google-fevrier-2023","status":"publish","type":"post","link":"https:\/\/www.seopress.org\/fr\/newsroom\/actualites-seo\/actualite-google-fevrier-2023\/","title":{"rendered":"L\u2019actualit\u00e9 Google \u2013 F\u00e9vrier 2023"},"content":{"rendered":"<p>F\u00e9vrier 2023 restera certainement dans l\u2019histoire comme le mois o\u00f9 les robots conversationnels ont fait leur entr\u00e9e dans les moteurs de recherche. N\u00e9anmoins, jusqu\u2019\u00e0 pr\u00e9sent seul un faible pourcentage d\u2019utilisateurs des moteurs de recherche ont eu acc\u00e8s \u00e0 Google Bard ou ChatGPT sur Bing. F\u00e9vrier 2023 n\u2019\u00e9tait que le d\u00e9but.<\/p>\n<p>Bien que ces nouvelles fonctionnalit\u00e9s de chat aient \u00e9t\u00e9 une distraction majeure pour de nombreux professionnels des moteurs de recherche, des changements plus traditionnels ont continu\u00e9 d\u2019avoir un impact sur le classement, la visibilit\u00e9 et le trafic vers les sites \u00e0 partir de Google, qui reste toujours le moteur de recherche le plus utilis\u00e9 au monde (<a href=\"https:\/\/gs.statcounter.com\/search-engine-market-share#monthly-202202-202302\" target=\"_blank\" rel=\"nofollow noopener\">93,37 % de parts de march\u00e9 selon StatCounter<\/a>). Google a publi\u00e9 une mise \u00e0 jour officielle le 21 f\u00e9vrier et la volatilit\u00e9 des r\u00e9sultats de recherche a \u00e9galement \u00e9t\u00e9 d\u00e9tect\u00e9e \u00e0 trois autres p\u00e9riodes au cours du mois \u2013 sugg\u00e9rant que d\u2019autres changements que Bard \u00e9taient en cours chez Google.<\/p>\n<figure id=\"attachment_75069\" aria-labelledby=\"figcaption_attachment_75069\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/01-rank-ranger-2023-02.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-75069\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/01-rank-ranger-2023-02.png\" alt=\"&lt;a href=&quot;https:\/\/www.rankranger.com\/rank-risk-index&quot;&gt;Volatilit\u00e9 les r\u00e9sultats de recherche Google selon Rank Ranger&lt;\/a&gt;\" width=\"1200\" height=\"720\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/01-rank-ranger-2023-02.png 1200w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/01-rank-ranger-2023-02-768x461.png 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"figcaption_attachment_75069\" class=\"wp-caption-text mt-3 mb-5 fst-italic\"><a href=\"https:\/\/www.rankranger.com\/rank-risk-index\" target=\"_blank\" rel=\"nofollow noopener\">Volatilit\u00e9 les r\u00e9sultats de recherche Google selon Rank Ranger<\/a><\/figcaption><\/figure>\n<h1>21 f\u00e9vrier \u2013 Mise \u00e0 jour Product Reviews (international)<\/h1>\n<p>Google a annonc\u00e9 la publication de la mise \u00e0 jour de Product Reviews le 21 f\u00e9vrier avec <a href=\"https:\/\/twitter.com\/googlesearchc\/status\/1628153197515661312\" target=\"_blank\" rel=\"nofollow noopener\">un tweet sur le compte @googlesearchc<\/a> (en anglais). Selon ce tweet, la mise \u00e0 jour est toujours en cours de d\u00e9ploiement fin f\u00e9vrier et devrait se terminer d\u00e9but mars. Au cours de cette p\u00e9riode, nous pouvons nous attendre \u00e0 ce que le classement dans Google change plus fr\u00e9quemment et cela est notamment perceptible sur le graphique Rank Ranger ci-dessus avec des fluctuations not\u00e9es \u00e9lev\u00e9es (orange) et tr\u00e8s \u00e9lev\u00e9es (rouge) entre le 21 f\u00e9vrier et le 28 f\u00e9vrier.<\/p>\n<p>Il s\u2019agit de la sixi\u00e8me version \u00e0 ce jour du syst\u00e8me Product Reviews (publi\u00e9 pour la premi\u00e8re fois en <a href=\"https:\/\/www.seopress.org\/fr\/newsroom\/actualites-seo\/actualite-google-avril-2021\/\">avril 2021<\/a>), mais c\u2019est la premi\u00e8re version \u00e0 avoir un impact sur les langues autres que l\u2019anglais. Cette version verra l\u2019algorithme appliqu\u00e9 pour la premi\u00e8re fois dans les recherches en espagnol, allemand, fran\u00e7ais, italien, vietnamien, indon\u00e9sien, russe, n\u00e9erlandais, portugais et polonais.<\/p>\n<p>L\u2019annonce de Google propose un lien vers la page de documentation, \u00ab\u00a0<a href=\"https:\/\/developers.google.com\/search\/updates\/product-reviews-update?hl=fr\" target=\"_blank\" rel=\"nofollow noopener\">Votre site Web et les mises \u00e0 jour des avis sur les produits dans les r\u00e9sultats de recherche Google<\/a> \u00bb. Cette page existait d\u00e9j\u00e0 mais elle a \u00e9t\u00e9 mise \u00e0 jour \u2013 en anglais du moins \u2013 afin d\u2019inclure les nouvelles langues. On note encore une fois la lenteur de Google \u00e0 mettre \u00e0 jour sa documentation en fran\u00e7ais !<\/p>\n<p>La mise \u00e0 jour des Product Reviews permet de s\u2019assurer que les articles d\u2019avis sur les produits (y compris les comparaisons de produits) sont bas\u00e9s sur une exp\u00e9rience utilisateur authentique et pas seulement sur un contenu cr\u00e9\u00e9 qui r\u00e9sumerait les informations existantes. Si vous pensez que votre site pourrait \u00eatre affect\u00e9 par cette mise \u00e0 jour, nous vous recommandons de consulter <a href=\"https:\/\/developers.google.com\/search\/docs\/specialty\/ecommerce\/write-high-quality-product-reviews\" target=\"_blank\" rel=\"nofollow noopener\">les directives de Google sur la fa\u00e7on de r\u00e9diger des avis de haute qualit\u00e9<\/a>.<\/p>\n<h1>Mises \u00e0 jour non confirm\u00e9es<\/h1>\n<p>Rank Ranger (et d\u2019autres outils de suivi de classement) montre clairement que le classement des sites dans Google a \u00e9galement chang\u00e9 \u00e0 trois reprises. Pour <a href=\"https:\/\/www.seroundtable.com\/author\/barry-schwartz\/2.html\" target=\"_blank\" rel=\"nofollow noopener\">Barry Schwartz<\/a> r\u00e9dacteur pour le site Search Engine Roundtable (en anglais uniquement), des mises \u00e0 jour non confirm\u00e9es ont eu lieu le <a href=\"https:\/\/www.seroundtable.com\/february-4th-google-search-ranking-algorithm-update-34859.html\" target=\"_blank\" rel=\"nofollow noopener\">4 f\u00e9vrier<\/a>, <a href=\"https:\/\/www.seroundtable.com\/february-8th-9th-google-search-ranking-algorithm-update-34884.html\" target=\"_blank\" rel=\"nofollow noopener\">le 8\/9 f\u00e9vrier<\/a> et autour du <a href=\"https:\/\/www.seroundtable.com\/google-search-ranking-algorithm-update-around-february-14th-34912.html\" target=\"_blank\" rel=\"nofollow noopener\">14 f\u00e9vrier<\/a>.<\/p>\n<p>Les articles de Barry contiennent des \u00ab bavardages SEO \u00bb extraits de contributions trouv\u00e9es sur des forums SEO relatant des exp\u00e9riences de propri\u00e9taires de sites affect\u00e9s par des baisses de trafic au cours des m\u00eames p\u00e9riodes. Son analyse sugg\u00e8re que les fluctuations dans les outils de suivi des moteurs de recherche ainsi que les retours d\u2019exp\u00e9rience relat\u00e9s dans les forums, signifient que Google a vraiment chang\u00e9 quelque chose. Le fait que Google n\u2019ait pas communiqu\u00e9 sur une mise \u00e0 jour officielle pour ces dates signifie qu\u2019elles restent des mises \u00e0 jour non confirm\u00e9es.<\/p>\n<h1>Google Bard et Bing Chat lanc\u00e9s en f\u00e9vrier<\/h1>\n<p>Google et Bing ont tous deux lanc\u00e9 des fonctionnalit\u00e9s de chat aliment\u00e9s par l\u2019IA dans leurs moteurs de recherche d\u00e9but f\u00e9vrier. Google a battu Bing sur le fil en \u00e9tant le premier \u00e0 faire l\u2019annonce, mais \u00e0 la fin du mois de f\u00e9vrier, Bing Chat \u00e9tait davantage disponible et utilis\u00e9 que Google Bard.<\/p>\n<p>Google Bard a \u00e9t\u00e9 annonc\u00e9 le 6 f\u00e9vrier dans <a href=\"https:\/\/blog.google\/technology\/ai\/bard-google-ai-search-updates\/\" target=\"_blank\" rel=\"nofollow noopener\">un article de blog de Sundar Pichai<\/a> (en anglais uniquement). Ce dernier a d\u00e9clar\u00e9 que le service exp\u00e9rimental d\u2019IA conversationnelle, aliment\u00e9 par LaMDA, \u00e9tait mis \u00e0 la disposition de testeurs de confiance avec la volont\u00e9 de le mettre \u00e0 la disposition du public \u00ab dans les prochaines semaines \u00bb. Lors d\u2019un \u00e9v\u00e9nement \u00e0 Paris le 8 f\u00e9vrier, il a fait la d\u00e9monstration d\u2019une version de Bard en application autonome (comme ChatGPT), puis a pr\u00e9sent\u00e9 des fonctionnalit\u00e9s de chat int\u00e9gr\u00e9es aux r\u00e9sultats de recherche Google.<\/p>\n<p>Malheureusement, les r\u00e9sultats en ligne montraient Bard en train de donner une r\u00e9ponse incorrecte \u00e0 une question sur le t\u00e9lescope spatial James Webb \u2013 le t\u00e9lescope n\u2019\u00e9tait pas la premi\u00e8re source d\u2019images d\u2019exoplan\u00e8tes. Cet incident a provoqu\u00e9 une chute du cours de l\u2019action Google et pourrait \u00eatre la raison pour laquelle Bard n\u2019est pas encore largement disponible.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Bard is an experimental conversational AI service, powered by LaMDA. Built using our large language models and drawing on information from the web, it\u2019s a launchpad for curiosity and can help simplify complex topics \u2192 <a href=\"https:\/\/t.co\/fSp531xKy3\">https:\/\/t.co\/fSp531xKy3<\/a> <a href=\"https:\/\/t.co\/JecHXVmt8l\">pic.twitter.com\/JecHXVmt8l<\/a><\/p>\n<p>&mdash; Google (@Google) <a href=\"https:\/\/twitter.com\/Google\/status\/1622710355775393793?ref_src=twsrc%5Etfw\">February 6, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Le lendemain, le 7 f\u00e9vrier, <a href=\"https:\/\/blogs.microsoft.com\/blog\/2023\/02\/07\/reinventing-search-with-a-new-ai-powered-microsoft-bing-and-edge-your-copilot-for-the-web\/\" target=\"_blank\" rel=\"nofollow noopener\">Microsoft a annonc\u00e9 le lancement de Bing Chat<\/a>, une fonctionnalit\u00e9 bas\u00e9e sur ChatGPT int\u00e9gr\u00e9e au moteur de recherche Bing. Il y a une liste d\u2019attente pour pouvoir avoir acc\u00e8s \u00e0 cette fonctionnalit\u00e9, mais on pense que <a href=\"https:\/\/blogs.microsoft.com\/blog\/2023\/02\/22\/the-new-bing-preview-experience-arrives-on-bing-and-edge-mobile-apps-introducing-bing-now-in-skype\/\" target=\"_blank\" rel=\"nofollow noopener\">1 million d\u2019utilisateurs<\/a> ont d\u00e9j\u00e0 pu la tester. Bing Chat s\u2019int\u00e8gre aux r\u00e9sultats de recherche pour r\u00e9pondre aux requ\u00eates et s\u2019ouvre dans un nouvel onglet lorsqu\u2019une conversation est engag\u00e9e.<\/p>\n<figure id=\"attachment_75068\" aria-labelledby=\"figcaption_attachment_75068\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/02-bing-chat.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-75068\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/02-bing-chat.png\" alt=\"Bing Chat int\u00e9gr\u00e9 aux r\u00e9sultats de recherche Bing\" width=\"3840\" height=\"2160\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/02-bing-chat.png 3840w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/02-bing-chat-768x432.png 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/02-bing-chat-1536x864.png 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/02-bing-chat-2048x1152.png 2048w\" sizes=\"auto, (max-width: 3840px) 100vw, 3840px\" \/><\/a><figcaption id=\"figcaption_attachment_75068\" class=\"wp-caption-text mt-3 mb-5 fst-italic\">Bing Chat int\u00e9gr\u00e9 aux r\u00e9sultats de recherche Bing<\/figcaption><\/figure>\n<figure id=\"attachment_75070\" aria-labelledby=\"figcaption_attachment_75070\" class=\"wp-caption aligncenter\" ><a href=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/03-bing-chat.png\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-75070\" src=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/03-bing-chat.png\" alt=\"Bing Chat en tant qu\u2019onglet s\u00e9par\u00e9 pour les r\u00e9sultats de recherche\" width=\"3840\" height=\"2160\" srcset=\"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/03-bing-chat.png 3840w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/03-bing-chat-768x432.png 768w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/03-bing-chat-1536x864.png 1536w, https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/03\/03-bing-chat-2048x1152.png 2048w\" sizes=\"auto, (max-width: 3840px) 100vw, 3840px\" \/><\/a><figcaption id=\"figcaption_attachment_75070\" class=\"wp-caption-text mt-3 mb-5 fst-italic\">Bing Chat en tant qu\u2019onglet s\u00e9par\u00e9 pour les r\u00e9sultats de recherche<\/figcaption><\/figure>\n<p>Comme on peut le voir sur les captures d\u2019\u00e9cran ci-dessus, Bing cite des pages qui ont \u00e9t\u00e9 utilis\u00e9es comme sources pour g\u00e9n\u00e9rer une r\u00e9ponse. Cette fonctionnalit\u00e9 \u00e9tait quant \u00e0 elle absente des d\u00e9monstrations de Google Bard, ce qui faisait craindre aux propri\u00e9taires de sites que l\u2019introduction de Bard dans Google allait r\u00e9duire le trafic g\u00e9n\u00e9r\u00e9 vers leurs sites. Nous aurons certainement plus de nouvelles sur ce sujet le mois prochain.<\/p>\n<h1>Conseils de Google sur le contenu g\u00e9n\u00e9r\u00e9 par l\u2019IA<\/h1>\n<p>L\u2019engouement r\u00e9cent pour ChatGPT a sensibilis\u00e9 beaucoup de personnes sur les capacit\u00e9s de l\u2019IA \u00e0 g\u00e9n\u00e9rer du texte. En janvier, <a href=\"https:\/\/www.seopress.org\/fr\/newsroom\/nouveautes-produit\/seopress-6-3\/\">SEOPress PRO a int\u00e9gr\u00e9 une fonctionnalit\u00e9 g\u00e9niale permettant de g\u00e9n\u00e9rer du contenu pertinent pour les balises TITLE et META Description<\/a> \u00e0 l\u2019aide de la technologie GPT d\u2019OpenAI. D\u2019autres logiciels bas\u00e9s sur GPT proposent d\u2019\u00e9crire des articles complets, des descriptions de produits et d\u2019autres contenus pour les sites.<\/p>\n<p>Cela conduit \u00e0 se demander si le contenu g\u00e9n\u00e9r\u00e9 par l\u2019IA est bon pour le r\u00e9f\u00e9rencement. Dans une tentative pour r\u00e9pondre \u00e0 cette question, Danny Sullivan et Chris Nelson de Google ont publi\u00e9 l\u2019article \u00ab <a href=\"https:\/\/developers.google.com\/search\/blog\/2023\/02\/google-search-and-ai-content?hl=fr\" target=\"_blank\" rel=\"nofollow noopener\">Conseils de la recherche Google concernant le contenu g\u00e9n\u00e9r\u00e9 par IA<\/a> \u00bb le 8 f\u00e9vrier.<\/p>\n<p>La r\u00e9ponse est sans doute un peu floue, mais elle indique toutefois clairement que Google ne disqualifiera pas le contenu simplement parce qu\u2019il est g\u00e9n\u00e9r\u00e9 ou assist\u00e9 par l\u2019IA. Les deux auteurs affirment que Google lutte depuis des ann\u00e9es contre le contenu de mauvaise qualit\u00e9 cr\u00e9\u00e9 en masse et qu\u2019il continuera d\u2019\u00eatre en mesure de filtrer le spam du contenu utile en utilisant sa technologie actuelle. Ils conseillent aux cr\u00e9ateurs de contenu de consulter les directives de Google pour <a href=\"https:\/\/developers.google.com\/search\/docs\/fundamentals\/creating-helpful-content?hl=fr\" target=\"_blank\" rel=\"nofollow noopener\">cr\u00e9er du contenu utile, fiable et ax\u00e9 sur les l\u2019humain <\/a>publi\u00e9 avec la mise \u00e0 jour Helpful Content et que \u00ab <em>les personnes souhaitant r\u00e9ussir sur la recherche Google doivent chercher \u00e0 produire des contenus originaux, de haute qualit\u00e9 et people-first, pr\u00e9sentant les qualit\u00e9s de l&rsquo;E-E-A-T<\/em> \u00bb et ne pas utiliser \u00ab <em>l&rsquo;IA comme un moyen simple et bon march\u00e9 de manipuler les classements dans les moteurs de recherche<\/em> \u00bb.<\/p>\n<h1>Meilleures pratiques pour les liens<\/h1>\n<p>Parmi les autres conseils publi\u00e9s par Google en f\u00e9vrier, se trouve un nouveau document tr\u00e8s utile mis \u00e0 jour le 20 f\u00e9vrier <a href=\"https:\/\/developers.google.com\/search\/docs\/crawling-indexing\/links-crawlable?hl=en\" target=\"_blank\" rel=\"nofollow noopener\">en anglais uniquement<\/a> (la version fran\u00e7aise devrait \u00eatre mise \u00e0 jour dans les jours \u00e0 venir) sur les <a href=\"https:\/\/developers.google.com\/search\/docs\/crawling-indexing\/links-crawlable?hl=fr\" target=\"_blank\" rel=\"nofollow noopener\">meilleures pratiques concernant les liens<\/a>. Ce document rappelle aux propri\u00e9taires de sites que Google utilise les liens comme un signal afin de d\u00e9terminer la pertinence des pages et fournit quelques rappels basiques, mais utiles, sur la fa\u00e7on dont les liens doivent \u00eatre ajout\u00e9s aux pages, qu\u2019ils soient internes (liens vers d\u2019autres pages de votre site) ou externes (liens vers d\u2019autres sites).<\/p>\n<p>Sur la section qui traite du texte d\u2019ancrage, Google nous conseille d\u2019\u00e9viter les liens utilisant du texte tel que \u00ab <a href=\"https:\/\/developers.google.com\/search\/docs\/crawling-indexing\/links-crawlable?hl=en\" target=\"_blank\" rel=\"nofollow noopener\">Cliquez ici<\/a> \u00bb ou \u00ab <a href=\"https:\/\/developers.google.com\/search\/docs\/crawling-indexing\/links-crawlable?hl=en\" target=\"_blank\" rel=\"nofollow noopener\">En savoir plus<\/a> \u00bb, \u00ab site web \u00bb ou \u00ab article \u00bb.<\/p>\n<p>La derni\u00e8re section confirme qu\u2019il ne faut pas avoir peur de cr\u00e9er des liens sortants vers d\u2019autres sites et sugg\u00e8re que l\u2019ajout de liens sortants peut \u00eatre b\u00e9n\u00e9fique pour le classement car cela permet d\u2019\u00e9tablir la \u00ab fiabilit\u00e9 \u00bb d\u2019un site \u2013 la fiabilit\u00e9 \u00e9tant un facteur de \u00ab E-E-A-T \u00bb.<\/p>\n<p>Pour rappel, E-E-A-T est le synonyme de 4 mots anglais : <em>Experience, Expertise, Authoritativeness <\/em>et<em> Trustworthiness<\/em>que nous pouvons traduire en fran\u00e7ais par : exp\u00e9rience, expertise, faisant autorit\u00e9 et fiabilit\u00e9. Ce sont des \u00e9l\u00e9ments que Google essaie de r\u00e9compenser \u00e0 travers le classement des pages dans les r\u00e9sultats de recherche. Le E-E-A-T va devenir un concept cl\u00e9 pour Google afin de trier le bon du mauvais contenu dans les semaines, mois et ann\u00e9es \u00e0 l\u2019avenir.<\/p>\n<p style=\"font-weight: 400;\">Vous voulez en savoir plus \u00e0 propos de E-A-T pour WordPress, lisez notre article <a href=\"https:\/\/www.seopress.org\/fr\/newsroom\/reportage\/optimiser-votre-site-wordpress-pour-google-eat\/\">Optimiser votre site WordPress pour Google EAT<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00e9vrier 2023 restera certainement dans l\u2019histoire comme le mois o\u00f9 les robots conversationnels ont&#8230;<\/p>\n","protected":false},"author":1,"featured_media":72548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"Le mois de f\u00e9vrier 2023 restera peut-\u00eatre dans l'histoire comme celui de l'arriv\u00e9e de la messagerie instantan\u00e9e aliment\u00e9e par l'IA dans Google et Bing, mais les impacts r\u00e9els sur le classement et le trafic proviennent d'autres sources, notamment la mise \u00e0 jour des avis sur les produits.","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"Le mois de f\u00e9vrier 2023 restera peut-\u00eatre dans l'histoire comme celui de l'arriv\u00e9e de la messagerie instantan\u00e9e aliment\u00e9e par l'IA dans Google et Bing, mais les impacts r\u00e9els sur le classement et le trafic proviennent d'autres sources, notamment la mise \u00e0 jour des avis sur les produits.","_seopress_social_fb_img":"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/02\/google-news-fr--2--february@2x-scaled.jpg","_seopress_social_fb_img_attachment_id":72552,"_seopress_social_fb_img_width":2560,"_seopress_social_fb_img_height":1280,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"Le mois de f\u00e9vrier 2023 restera peut-\u00eatre dans l'histoire comme celui de l'arriv\u00e9e de la messagerie instantan\u00e9e aliment\u00e9e par l'IA dans Google et Bing, mais les impacts r\u00e9els sur le classement et le trafic proviennent d'autres sources, notamment la mise \u00e0 jour des avis sur les produits.","_seopress_social_twitter_img":"https:\/\/www.seopress.org\/fr\/wp-content\/uploads\/sites\/2\/2023\/02\/google-news-fr--2--february@2x-scaled.jpg","_seopress_social_twitter_img_attachment_id":72552,"_seopress_social_twitter_img_width":2560,"_seopress_social_twitter_img_height":1280,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"both","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[{"_seopress_pro_rich_snippets_type":"none"}],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","editor_notices":[],"footnotes":""},"categories":[99],"tags":[134,127],"class_list":["post-72546","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualites-seo","tag-ia","tag-indexation-google-bing"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/posts\/72546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/comments?post=72546"}],"version-history":[{"count":0,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/posts\/72546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/media\/72548"}],"wp:attachment":[{"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/media?parent=72546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/categories?post=72546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.seopress.org\/fr\/wp-json\/wp\/v2\/tags?post=72546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}